{"id":11715,"date":"2019-12-20T16:40:54","date_gmt":"2019-12-20T19:40:54","guid":{"rendered":"http:\/\/www.nuxcell.com.br?p=11715"},"modified":"2019-12-20T16:40:54","modified_gmt":"2019-12-20T19:40:54","slug":"obesidade-em-caes-e-gatos-quem-e-o-grande-vilao","status":"publish","type":"post","link":"https:\/\/www.biosyn.com.br\/nuxcell\/obesidade-em-caes-e-gatos-quem-e-o-grande-vilao\/","title":{"rendered":"Obesidade em c\u00e3es e gatos: quem \u00e9 o grande vil\u00e3o?"},"content":{"rendered":"\n<p>Tem se discutido muito o papel do tutor no controle do peso de seus animais, apesar de fatores gen\u00e9ticos e hormonais tamb\u00e9m estarem relacionados a esse balan\u00e7o energ\u00e9tico positivo que o animal pode desenvolver, fatores comportamentais do tutor tamb\u00e9m contribuem no desenvolvimento do sobrepeso em c\u00e3es e gatos.<\/p>\n\n\n\n<p>Um dos fatores que podem contribuir \u00e9 o habitual oferecimento de petiscos de mesa, que s\u00e3o peda\u00e7os de alimentos do consumo humano que o tutor para n\u00e3o jogar fora ou por &#8216;d\u00f3&#8217; acaba oferecendo ao seu animal, a alimenta\u00e7\u00e3o n\u00e3o controlada e ofertada \u00e0 vontade tamb\u00e9m estimulam ao n\u00e3o controle da ingest\u00e3o di\u00e1ria de alimentos. A presen\u00e7a do animal em cozinhas e ao lado da mesa aonde seus tutores se alimentam contribuem para o oferecimento exagerado de petiscos.<\/p>\n\n\n\n<p>Busque orienta\u00e7\u00e3o com o m\u00e9dico veterin\u00e1rio do seu animal para poder formular uma dieta balanceada ao seu animal, e tamb\u00e9m verificar no caso de c\u00e3es obesos se outros fatores, como doen\u00e7as hormonais, podem estar relacionados ao quadro de obesidade.<\/p>\n\n\n\n<p>Al\u00e9m disso, a predisposi\u00e7\u00e3o ao sobrepeso \u00e9 quando h\u00e1 uma alta ingest\u00e3o cal\u00f3rica com menor gasto energ\u00e9tico, portanto inserir uma rotina de caminhada e brincadeiras ao ar livre estimula o gasto energ\u00e9tico do seu pet.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Tem se discutido muito o papel do tutor no controle do peso de seus animais, apesar de fatores gen\u00e9ticos e hormonais tamb\u00e9m estarem relacionados a esse balan\u00e7o energ\u00e9tico positivo que o animal pode desenvolver, fatores comportamentais do tutor tamb\u00e9m contribuem no desenvolvimento do sobrepeso em c\u00e3es e gatos. Um dos fatores que podem contribuir \u00e9 [&hellip;]<\/p>\n","protected":false},"author":4,"featured_media":11716,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"footnotes":""},"categories":[28],"tags":[],"class_list":["post-11715","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-saude"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v26.2 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>Obesidade em c\u00e3es e gatos: quem \u00e9 o grande vil\u00e3o? - NUXCELL\u00ae | Muito mais que vitamina para cachorro e gato!<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.biosyn.com.br\/nuxcell\/obesidade-em-caes-e-gatos-quem-e-o-grande-vilao\/\" \/>\n<meta property=\"og:locale\" content=\"pt_BR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Obesidade em c\u00e3es e gatos: quem \u00e9 o grande vil\u00e3o? - NUXCELL\u00ae | Muito mais que vitamina para cachorro e gato!\" \/>\n<meta property=\"og:description\" content=\"Tem se discutido muito o papel do tutor no controle do peso de seus animais, apesar de fatores gen\u00e9ticos e hormonais tamb\u00e9m estarem relacionados a esse balan\u00e7o energ\u00e9tico positivo que o animal pode desenvolver, fatores comportamentais do tutor tamb\u00e9m contribuem no desenvolvimento do sobrepeso em c\u00e3es e gatos. Um dos fatores que podem contribuir \u00e9 [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.biosyn.com.br\/nuxcell\/obesidade-em-caes-e-gatos-quem-e-o-grande-vilao\/\" \/>\n<meta property=\"og:site_name\" content=\"NUXCELL\u00ae | Muito mais que vitamina para cachorro e gato!\" \/>\n<meta property=\"article:published_time\" content=\"2019-12-20T19:40:54+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.biosyn.com.br\/nuxcell\/wp-content\/uploads\/sites\/2\/2019\/12\/5dfd23a0d8819.png\" \/>\n\t<meta property=\"og:image:width\" content=\"1024\" \/>\n\t<meta property=\"og:image:height\" content=\"682\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/png\" \/>\n<meta name=\"author\" content=\"BioSyn\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t<meta name=\"twitter:data1\" content=\"BioSyn\" \/>\n\t<meta name=\"twitter:label2\" content=\"Est. tempo de leitura\" \/>\n\t<meta name=\"twitter:data2\" content=\"1 minuto\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\/\/www.biosyn.com.br\/nuxcell\/obesidade-em-caes-e-gatos-quem-e-o-grande-vilao\/#article\",\"isPartOf\":{\"@id\":\"https:\/\/www.biosyn.com.br\/nuxcell\/obesidade-em-caes-e-gatos-quem-e-o-grande-vilao\/\"},\"author\":{\"name\":\"BioSyn\",\"@id\":\"https:\/\/www.biosyn.com.br\/nuxcell\/#\/schema\/person\/be2390874bdf6faf4777647b519e5141\"},\"headline\":\"Obesidade em c\u00e3es e gatos: quem \u00e9 o grande vil\u00e3o?\",\"datePublished\":\"2019-12-20T19:40:54+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\/\/www.biosyn.com.br\/nuxcell\/obesidade-em-caes-e-gatos-quem-e-o-grande-vilao\/\"},\"wordCount\":236,\"publisher\":{\"@id\":\"https:\/\/www.biosyn.com.br\/nuxcell\/#organization\"},\"image\":{\"@id\":\"https:\/\/www.biosyn.com.br\/nuxcell\/obesidade-em-caes-e-gatos-quem-e-o-grande-vilao\/#primaryimage\"},\"thumbnailUrl\":\"https:\/\/www.biosyn.com.br\/nuxcell\/wp-content\/uploads\/sites\/2\/2019\/12\/5dfd23a0d8819.png\",\"articleSection\":[\"Sa\u00fade\"],\"inLanguage\":\"pt-BR\"},{\"@type\":\"WebPage\",\"@id\":\"https:\/\/www.biosyn.com.br\/nuxcell\/obesidade-em-caes-e-gatos-quem-e-o-grande-vilao\/\",\"url\":\"https:\/\/www.biosyn.com.br\/nuxcell\/obesidade-em-caes-e-gatos-quem-e-o-grande-vilao\/\",\"name\":\"Obesidade em c\u00e3es e gatos: quem \u00e9 o grande vil\u00e3o? - NUXCELL\u00ae | Muito mais que vitamina para cachorro e gato!\",\"isPartOf\":{\"@id\":\"https:\/\/www.biosyn.com.br\/nuxcell\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\/\/www.biosyn.com.br\/nuxcell\/obesidade-em-caes-e-gatos-quem-e-o-grande-vilao\/#primaryimage\"},\"image\":{\"@id\":\"https:\/\/www.biosyn.com.br\/nuxcell\/obesidade-em-caes-e-gatos-quem-e-o-grande-vilao\/#primaryimage\"},\"thumbnailUrl\":\"https:\/\/www.biosyn.com.br\/nuxcell\/wp-content\/uploads\/sites\/2\/2019\/12\/5dfd23a0d8819.png\",\"datePublished\":\"2019-12-20T19:40:54+00:00\",\"breadcrumb\":{\"@id\":\"https:\/\/www.biosyn.com.br\/nuxcell\/obesidade-em-caes-e-gatos-quem-e-o-grande-vilao\/#breadcrumb\"},\"inLanguage\":\"pt-BR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/www.biosyn.com.br\/nuxcell\/obesidade-em-caes-e-gatos-quem-e-o-grande-vilao\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"pt-BR\",\"@id\":\"https:\/\/www.biosyn.com.br\/nuxcell\/obesidade-em-caes-e-gatos-quem-e-o-grande-vilao\/#primaryimage\",\"url\":\"https:\/\/www.biosyn.com.br\/nuxcell\/wp-content\/uploads\/sites\/2\/2019\/12\/5dfd23a0d8819.png\",\"contentUrl\":\"https:\/\/www.biosyn.com.br\/nuxcell\/wp-content\/uploads\/sites\/2\/2019\/12\/5dfd23a0d8819.png\",\"width\":1024,\"height\":682},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/www.biosyn.com.br\/nuxcell\/obesidade-em-caes-e-gatos-quem-e-o-grande-vilao\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"In\u00edcio\",\"item\":\"https:\/\/www.biosyn.com.br\/nuxcell\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Obesidade em c\u00e3es e gatos: quem \u00e9 o grande vil\u00e3o?\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/www.biosyn.com.br\/nuxcell\/#website\",\"url\":\"https:\/\/www.biosyn.com.br\/nuxcell\/\",\"name\":\"NUXCELL\u00ae | Muito mais que vitamina para cachorro e gato!\",\"description\":\"NUXCELL\u00ae \u00e9 um simbi\u00f3tico imunomodulador exclusivo para c\u00e3es e gatos. Fortalece as defesas do organismo e fornece nutrientes estrat\u00e9gicos para a sa\u00fade pet.\",\"publisher\":{\"@id\":\"https:\/\/www.biosyn.com.br\/nuxcell\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/www.biosyn.com.br\/nuxcell\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"pt-BR\"},{\"@type\":\"Organization\",\"@id\":\"https:\/\/www.biosyn.com.br\/nuxcell\/#organization\",\"name\":\"NUXCELL\u00ae | Muito mais que vitamina para cachorro e gato!\",\"url\":\"https:\/\/www.biosyn.com.br\/nuxcell\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"pt-BR\",\"@id\":\"https:\/\/www.biosyn.com.br\/nuxcell\/#\/schema\/logo\/image\/\",\"url\":\"https:\/\/www.biosyn.com.br\/nuxcell\/wp-content\/uploads\/sites\/2\/2024\/07\/nuxcell_logo-e1721911131146.png\",\"contentUrl\":\"https:\/\/www.biosyn.com.br\/nuxcell\/wp-content\/uploads\/sites\/2\/2024\/07\/nuxcell_logo-e1721911131146.png\",\"width\":550,\"height\":122,\"caption\":\"NUXCELL\u00ae | Muito mais que vitamina para cachorro e gato!\"},\"image\":{\"@id\":\"https:\/\/www.biosyn.com.br\/nuxcell\/#\/schema\/logo\/image\/\"}},{\"@type\":\"Person\",\"@id\":\"https:\/\/www.biosyn.com.br\/nuxcell\/#\/schema\/person\/be2390874bdf6faf4777647b519e5141\",\"name\":\"BioSyn\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"pt-BR\",\"@id\":\"https:\/\/www.biosyn.com.br\/nuxcell\/#\/schema\/person\/image\/\",\"url\":\"https:\/\/secure.gravatar.com\/avatar\/9bfc9c12abb8906f5e67400cc2a2c0eff002384588f8b12c2106a45da6d6c84c?s=96&d=mm&r=g\",\"contentUrl\":\"https:\/\/secure.gravatar.com\/avatar\/9bfc9c12abb8906f5e67400cc2a2c0eff002384588f8b12c2106a45da6d6c84c?s=96&d=mm&r=g\",\"caption\":\"BioSyn\"},\"description\":\"Somos especialistas no desenvolvimento e produ\u00e7\u00e3o de simbi\u00f3ticos imunomoduladores, suplementos que combinam probi\u00f3ticos e prebi\u00f3ticos associados a nutrientes essenciais para a sa\u00fade animal.\",\"sameAs\":[\"https:\/\/www.nuxcell.com.br\/wp-admin\"],\"url\":\"https:\/\/www.biosyn.com.br\/nuxcell\/author\/marketing\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Obesidade em c\u00e3es e gatos: quem \u00e9 o grande vil\u00e3o? - NUXCELL\u00ae | Muito mais que vitamina para cachorro e gato!","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.biosyn.com.br\/nuxcell\/obesidade-em-caes-e-gatos-quem-e-o-grande-vilao\/","og_locale":"pt_BR","og_type":"article","og_title":"Obesidade em c\u00e3es e gatos: quem \u00e9 o grande vil\u00e3o? - NUXCELL\u00ae | Muito mais que vitamina para cachorro e gato!","og_description":"Tem se discutido muito o papel do tutor no controle do peso de seus animais, apesar de fatores gen\u00e9ticos e hormonais tamb\u00e9m estarem relacionados a esse balan\u00e7o energ\u00e9tico positivo que o animal pode desenvolver, fatores comportamentais do tutor tamb\u00e9m contribuem no desenvolvimento do sobrepeso em c\u00e3es e gatos. Um dos fatores que podem contribuir \u00e9 [&hellip;]","og_url":"https:\/\/www.biosyn.com.br\/nuxcell\/obesidade-em-caes-e-gatos-quem-e-o-grande-vilao\/","og_site_name":"NUXCELL\u00ae | Muito mais que vitamina para cachorro e gato!","article_published_time":"2019-12-20T19:40:54+00:00","og_image":[{"width":1024,"height":682,"url":"https:\/\/www.biosyn.com.br\/nuxcell\/wp-content\/uploads\/sites\/2\/2019\/12\/5dfd23a0d8819.png","type":"image\/png"}],"author":"BioSyn","twitter_card":"summary_large_image","twitter_misc":{"Escrito por":"BioSyn","Est. tempo de leitura":"1 minuto"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/www.biosyn.com.br\/nuxcell\/obesidade-em-caes-e-gatos-quem-e-o-grande-vilao\/#article","isPartOf":{"@id":"https:\/\/www.biosyn.com.br\/nuxcell\/obesidade-em-caes-e-gatos-quem-e-o-grande-vilao\/"},"author":{"name":"BioSyn","@id":"https:\/\/www.biosyn.com.br\/nuxcell\/#\/schema\/person\/be2390874bdf6faf4777647b519e5141"},"headline":"Obesidade em c\u00e3es e gatos: quem \u00e9 o grande vil\u00e3o?","datePublished":"2019-12-20T19:40:54+00:00","mainEntityOfPage":{"@id":"https:\/\/www.biosyn.com.br\/nuxcell\/obesidade-em-caes-e-gatos-quem-e-o-grande-vilao\/"},"wordCount":236,"publisher":{"@id":"https:\/\/www.biosyn.com.br\/nuxcell\/#organization"},"image":{"@id":"https:\/\/www.biosyn.com.br\/nuxcell\/obesidade-em-caes-e-gatos-quem-e-o-grande-vilao\/#primaryimage"},"thumbnailUrl":"https:\/\/www.biosyn.com.br\/nuxcell\/wp-content\/uploads\/sites\/2\/2019\/12\/5dfd23a0d8819.png","articleSection":["Sa\u00fade"],"inLanguage":"pt-BR"},{"@type":"WebPage","@id":"https:\/\/www.biosyn.com.br\/nuxcell\/obesidade-em-caes-e-gatos-quem-e-o-grande-vilao\/","url":"https:\/\/www.biosyn.com.br\/nuxcell\/obesidade-em-caes-e-gatos-quem-e-o-grande-vilao\/","name":"Obesidade em c\u00e3es e gatos: quem \u00e9 o grande vil\u00e3o? - NUXCELL\u00ae | Muito mais que vitamina para cachorro e gato!","isPartOf":{"@id":"https:\/\/www.biosyn.com.br\/nuxcell\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.biosyn.com.br\/nuxcell\/obesidade-em-caes-e-gatos-quem-e-o-grande-vilao\/#primaryimage"},"image":{"@id":"https:\/\/www.biosyn.com.br\/nuxcell\/obesidade-em-caes-e-gatos-quem-e-o-grande-vilao\/#primaryimage"},"thumbnailUrl":"https:\/\/www.biosyn.com.br\/nuxcell\/wp-content\/uploads\/sites\/2\/2019\/12\/5dfd23a0d8819.png","datePublished":"2019-12-20T19:40:54+00:00","breadcrumb":{"@id":"https:\/\/www.biosyn.com.br\/nuxcell\/obesidade-em-caes-e-gatos-quem-e-o-grande-vilao\/#breadcrumb"},"inLanguage":"pt-BR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.biosyn.com.br\/nuxcell\/obesidade-em-caes-e-gatos-quem-e-o-grande-vilao\/"]}]},{"@type":"ImageObject","inLanguage":"pt-BR","@id":"https:\/\/www.biosyn.com.br\/nuxcell\/obesidade-em-caes-e-gatos-quem-e-o-grande-vilao\/#primaryimage","url":"https:\/\/www.biosyn.com.br\/nuxcell\/wp-content\/uploads\/sites\/2\/2019\/12\/5dfd23a0d8819.png","contentUrl":"https:\/\/www.biosyn.com.br\/nuxcell\/wp-content\/uploads\/sites\/2\/2019\/12\/5dfd23a0d8819.png","width":1024,"height":682},{"@type":"BreadcrumbList","@id":"https:\/\/www.biosyn.com.br\/nuxcell\/obesidade-em-caes-e-gatos-quem-e-o-grande-vilao\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"In\u00edcio","item":"https:\/\/www.biosyn.com.br\/nuxcell\/"},{"@type":"ListItem","position":2,"name":"Obesidade em c\u00e3es e gatos: quem \u00e9 o grande vil\u00e3o?"}]},{"@type":"WebSite","@id":"https:\/\/www.biosyn.com.br\/nuxcell\/#website","url":"https:\/\/www.biosyn.com.br\/nuxcell\/","name":"NUXCELL\u00ae | Muito mais que vitamina para cachorro e gato!","description":"NUXCELL\u00ae \u00e9 um simbi\u00f3tico imunomodulador exclusivo para c\u00e3es e gatos. Fortalece as defesas do organismo e fornece nutrientes estrat\u00e9gicos para a sa\u00fade pet.","publisher":{"@id":"https:\/\/www.biosyn.com.br\/nuxcell\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.biosyn.com.br\/nuxcell\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"pt-BR"},{"@type":"Organization","@id":"https:\/\/www.biosyn.com.br\/nuxcell\/#organization","name":"NUXCELL\u00ae | Muito mais que vitamina para cachorro e gato!","url":"https:\/\/www.biosyn.com.br\/nuxcell\/","logo":{"@type":"ImageObject","inLanguage":"pt-BR","@id":"https:\/\/www.biosyn.com.br\/nuxcell\/#\/schema\/logo\/image\/","url":"https:\/\/www.biosyn.com.br\/nuxcell\/wp-content\/uploads\/sites\/2\/2024\/07\/nuxcell_logo-e1721911131146.png","contentUrl":"https:\/\/www.biosyn.com.br\/nuxcell\/wp-content\/uploads\/sites\/2\/2024\/07\/nuxcell_logo-e1721911131146.png","width":550,"height":122,"caption":"NUXCELL\u00ae | Muito mais que vitamina para cachorro e gato!"},"image":{"@id":"https:\/\/www.biosyn.com.br\/nuxcell\/#\/schema\/logo\/image\/"}},{"@type":"Person","@id":"https:\/\/www.biosyn.com.br\/nuxcell\/#\/schema\/person\/be2390874bdf6faf4777647b519e5141","name":"BioSyn","image":{"@type":"ImageObject","inLanguage":"pt-BR","@id":"https:\/\/www.biosyn.com.br\/nuxcell\/#\/schema\/person\/image\/","url":"https:\/\/secure.gravatar.com\/avatar\/9bfc9c12abb8906f5e67400cc2a2c0eff002384588f8b12c2106a45da6d6c84c?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/9bfc9c12abb8906f5e67400cc2a2c0eff002384588f8b12c2106a45da6d6c84c?s=96&d=mm&r=g","caption":"BioSyn"},"description":"Somos especialistas no desenvolvimento e produ\u00e7\u00e3o de simbi\u00f3ticos imunomoduladores, suplementos que combinam probi\u00f3ticos e prebi\u00f3ticos associados a nutrientes essenciais para a sa\u00fade animal.","sameAs":["https:\/\/www.nuxcell.com.br\/wp-admin"],"url":"https:\/\/www.biosyn.com.br\/nuxcell\/author\/marketing\/"}]}},"_links":{"self":[{"href":"https:\/\/www.biosyn.com.br\/nuxcell\/wp-json\/wp\/v2\/posts\/11715","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.biosyn.com.br\/nuxcell\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.biosyn.com.br\/nuxcell\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.biosyn.com.br\/nuxcell\/wp-json\/wp\/v2\/users\/4"}],"replies":[{"embeddable":true,"href":"https:\/\/www.biosyn.com.br\/nuxcell\/wp-json\/wp\/v2\/comments?post=11715"}],"version-history":[{"count":0,"href":"https:\/\/www.biosyn.com.br\/nuxcell\/wp-json\/wp\/v2\/posts\/11715\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.biosyn.com.br\/nuxcell\/wp-json\/wp\/v2\/media\/11716"}],"wp:attachment":[{"href":"https:\/\/www.biosyn.com.br\/nuxcell\/wp-json\/wp\/v2\/media?parent=11715"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.biosyn.com.br\/nuxcell\/wp-json\/wp\/v2\/categories?post=11715"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.biosyn.com.br\/nuxcell\/wp-json\/wp\/v2\/tags?post=11715"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}