{"id":16295,"date":"2022-09-22T14:15:50","date_gmt":"2022-09-22T17:15:50","guid":{"rendered":"https:\/\/www.nuxcell.com.br?p=16295"},"modified":"2022-09-22T14:15:50","modified_gmt":"2022-09-22T17:15:50","slug":"qual-a-importancia-da-taurina-para-gatos","status":"publish","type":"post","link":"https:\/\/www.biosyn.com.br\/nuxcell\/qual-a-importancia-da-taurina-para-gatos\/","title":{"rendered":"Qual a import\u00e2ncia da taurina para gatos?"},"content":{"rendered":"<p><span style=\"color: #000000;\"><em>Os amino\u00e1cidos n\u00e3o essenciais s\u00e3o os que o pr\u00f3prio organismo sintetiza, enquanto os essenciais n\u00e3o s\u00e3o produzidos pelo organismo e precisam ser inclu\u00eddos nas dietas.<\/em><\/span><\/p>\n<p><span style=\"color: #000000;\"><strong>Para que serve taurina em gatos?<\/strong><\/span><\/p>\n<p><span style=\"color: #000000;\">Grande parte dos mam\u00edferos sintetiza a taurina, inclusive os seres humanos. Por\u00e9m, os gatos n\u00e3o produzem em quantidades suficientes, e \u00e9 por isso que precisam obt\u00ea-la por meio da sua alimenta\u00e7\u00e3o. Isso significa que a taurina \u00e9 um amino\u00e1cido essencial para os gatos, mas n\u00e3o essencial para os demais animais.<\/span><\/p>\n<p><span style=\"color: #000000;\">A taurina \u00e9 primordial para o funcionamento do cora\u00e7\u00e3o, da vis\u00e3o e do sistema reprodutivo dos animais, al\u00e9m de participar da forma\u00e7\u00e3o da bile, sendo um importante agente na digest\u00e3o.<\/span><\/p>\n<p><span style=\"color: #000000;\"><strong><img fetchpriority=\"high\" decoding=\"async\" class=\"wp-image-16299 aligncenter\" src=\"https:\/\/www.biosyn.com.br\/nuxcellwp-content\/uploads\/sites\/2\/2022\/09\/gray-kitty-with-monochrome-wall-her-300x191.jpg\" alt=\"\" width=\"569\" height=\"362\" \/><\/strong><\/span><\/p>\n<p><span style=\"color: #000000;\"><strong>Os gatos que apresentam defici\u00eancia desse amino\u00e1cido no organismo podem manifestar as seguintes patologias:<\/strong><\/span><\/p>\n<ul>\n<li><span style=\"color: #000000;\">Perda gradual da vis\u00e3o at\u00e9 a completa cegueira;<\/span><\/li>\n<li><span style=\"color: #000000;\">Falhas reprodutivas e desenvolvimento fetal insuficiente (abortos e fetos com hidrocefalia ou anencefalia)<\/span><\/li>\n<li><span style=\"color: #000000;\">\u00a0Cardiomiopatia dilatada (CMD) (doen\u00e7a degenerativa do m\u00fasculo card\u00edaco);<\/span><\/li>\n<li><span style=\"color: #000000;\">Perda da audi\u00e7\u00e3o;<\/span><\/li>\n<li><span style=\"color: #000000;\">Disfun\u00e7\u00e3o imunol\u00f3gica.<\/span><\/li>\n<li><span style=\"color: #000000;\">Benef\u00edcios que o amino\u00e1cido proporciona aos felinos:<\/span><\/li>\n<li><span style=\"color: #000000;\">\u00a0A\u00e7\u00e3o antioxidante (ajuda a combater o envelhecimento e a aumentar a expectativa de vida);<\/span><\/li>\n<li><span style=\"color: #000000;\">Regula os n\u00edveis de s\u00f3dio e \u00e1gua nas c\u00e9lulas;<\/span><\/li>\n<li><span style=\"color: #000000;\">Estimula o metabolismo e o crescimento muscular);<\/span><\/li>\n<li><span style=\"color: #000000;\"> Atua na produ\u00e7\u00e3o dos sais biliares (melhorando a digest\u00e3o;<\/span><\/li>\n<li><span style=\"color: #000000;\">A\u00e7\u00e3o neurotransmissora (age nas c\u00e9lulas do sistema nervoso);<\/span><\/li>\n<li><span style=\"color: #000000;\">Atua de forma positiva nas c\u00e9lulas da retina.<\/span><\/li>\n<\/ul>\n<p><span style=\"color: #000000;\"><strong><img decoding=\"async\" class=\"wp-image-16302 aligncenter\" src=\"https:\/\/www.biosyn.com.br\/nuxcellwp-content\/uploads\/sites\/2\/2022\/09\/beautiful-cat-portrait-close-up-1-300x200.jpg\" alt=\"\" width=\"596\" height=\"397\" \/><\/strong><\/span><\/p>\n<p><span style=\"color: #000000;\"><strong>Onde encontrar a taurina?<\/strong><\/span><\/p>\n<p><span style=\"color: #000000;\">A taurina perde as suas propriedades quando \u00e9 exposta a altas temperaturas. Dessa forma, os alimentos devem ser preferencialmente disponibilizados crus e frescos aos felinos.<\/span><\/p>\n<ul>\n<li><span style=\"color: #000000;\">Ra\u00e7\u00f5es equilibradas;<\/span><\/li>\n<li><span style=\"color: #000000;\">V\u00edsceras de bovinos e aves;<\/span><\/li>\n<li><span style=\"color: #000000;\">Mexilh\u00f5es e camar\u00f5es;<\/span><\/li>\n<li><span style=\"color: #000000;\">Ovos e latic\u00ednios;<\/span><\/li>\n<li><a href=\"\/?page_id=11171&amp;v=19d3326f3137\"><span style=\"color: #000000;\">Nuxcell FEL.<\/span><\/a><\/li>\n<\/ul>\n<p>&nbsp;<\/p>\n<p><em><span style=\"color: #000000;\">Texto: Larissa Campello &#8211; M\u00e9dica Veterin\u00e1ria &#8211; CRMV <\/span><\/em>17942<\/p>\n<p>&nbsp;<\/p>\n<p>&nbsp;<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Os amino\u00e1cidos n\u00e3o essenciais s\u00e3o os que o pr\u00f3prio organismo sintetiza, enquanto os essenciais n\u00e3o s\u00e3o produzidos pelo organismo e precisam ser inclu\u00eddos nas dietas. Para que serve taurina em gatos? Grande parte dos mam\u00edferos sintetiza a taurina, inclusive os seres humanos. Por\u00e9m, os gatos n\u00e3o produzem em quantidades suficientes, e \u00e9 por isso que [&hellip;]<\/p>\n","protected":false},"author":4,"featured_media":16296,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"footnotes":""},"categories":[30,28],"tags":[31],"class_list":["post-16295","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-nutricao","category-saude","tag-nuxcell-fel"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v26.2 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>Qual a import\u00e2ncia da taurina para gatos? - NUXCELL\u00ae | Muito mais que vitamina para cachorro e gato!<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.biosyn.com.br\/nuxcell\/qual-a-importancia-da-taurina-para-gatos\/\" \/>\n<meta property=\"og:locale\" content=\"pt_BR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Qual a import\u00e2ncia da taurina para gatos? - NUXCELL\u00ae | Muito mais que vitamina para cachorro e gato!\" \/>\n<meta property=\"og:description\" content=\"Os amino\u00e1cidos n\u00e3o essenciais s\u00e3o os que o pr\u00f3prio organismo sintetiza, enquanto os essenciais n\u00e3o s\u00e3o produzidos pelo organismo e precisam ser inclu\u00eddos nas dietas. Para que serve taurina em gatos? Grande parte dos mam\u00edferos sintetiza a taurina, inclusive os seres humanos. Por\u00e9m, os gatos n\u00e3o produzem em quantidades suficientes, e \u00e9 por isso que [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.biosyn.com.br\/nuxcell\/qual-a-importancia-da-taurina-para-gatos\/\" \/>\n<meta property=\"og:site_name\" content=\"NUXCELL\u00ae | Muito mais que vitamina para cachorro e gato!\" \/>\n<meta property=\"article:published_time\" content=\"2022-09-22T17:15:50+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.biosyn.com.br\/nuxcell\/wp-content\/uploads\/sites\/2\/2022\/09\/adorable-kitty-with-monochrome-wall-her-scaled-1.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"2560\" \/>\n\t<meta property=\"og:image:height\" content=\"1829\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"BioSyn\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t<meta name=\"twitter:data1\" content=\"BioSyn\" \/>\n\t<meta name=\"twitter:label2\" content=\"Est. tempo de leitura\" \/>\n\t<meta name=\"twitter:data2\" content=\"2 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\/\/www.biosyn.com.br\/nuxcell\/qual-a-importancia-da-taurina-para-gatos\/#article\",\"isPartOf\":{\"@id\":\"https:\/\/www.biosyn.com.br\/nuxcell\/qual-a-importancia-da-taurina-para-gatos\/\"},\"author\":{\"name\":\"BioSyn\",\"@id\":\"https:\/\/www.biosyn.com.br\/nuxcell\/#\/schema\/person\/be2390874bdf6faf4777647b519e5141\"},\"headline\":\"Qual a import\u00e2ncia da taurina para gatos?\",\"datePublished\":\"2022-09-22T17:15:50+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\/\/www.biosyn.com.br\/nuxcell\/qual-a-importancia-da-taurina-para-gatos\/\"},\"wordCount\":326,\"publisher\":{\"@id\":\"https:\/\/www.biosyn.com.br\/nuxcell\/#organization\"},\"image\":{\"@id\":\"https:\/\/www.biosyn.com.br\/nuxcell\/qual-a-importancia-da-taurina-para-gatos\/#primaryimage\"},\"thumbnailUrl\":\"https:\/\/www.biosyn.com.br\/nuxcell\/wp-content\/uploads\/sites\/2\/2022\/09\/adorable-kitty-with-monochrome-wall-her-scaled-1.jpg\",\"keywords\":[\"nuxcell fel\"],\"articleSection\":[\"Nutri\u00e7\u00e3o\",\"Sa\u00fade\"],\"inLanguage\":\"pt-BR\"},{\"@type\":\"WebPage\",\"@id\":\"https:\/\/www.biosyn.com.br\/nuxcell\/qual-a-importancia-da-taurina-para-gatos\/\",\"url\":\"https:\/\/www.biosyn.com.br\/nuxcell\/qual-a-importancia-da-taurina-para-gatos\/\",\"name\":\"Qual a import\u00e2ncia da taurina para gatos? - NUXCELL\u00ae | Muito mais que vitamina para cachorro e gato!\",\"isPartOf\":{\"@id\":\"https:\/\/www.biosyn.com.br\/nuxcell\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\/\/www.biosyn.com.br\/nuxcell\/qual-a-importancia-da-taurina-para-gatos\/#primaryimage\"},\"image\":{\"@id\":\"https:\/\/www.biosyn.com.br\/nuxcell\/qual-a-importancia-da-taurina-para-gatos\/#primaryimage\"},\"thumbnailUrl\":\"https:\/\/www.biosyn.com.br\/nuxcell\/wp-content\/uploads\/sites\/2\/2022\/09\/adorable-kitty-with-monochrome-wall-her-scaled-1.jpg\",\"datePublished\":\"2022-09-22T17:15:50+00:00\",\"breadcrumb\":{\"@id\":\"https:\/\/www.biosyn.com.br\/nuxcell\/qual-a-importancia-da-taurina-para-gatos\/#breadcrumb\"},\"inLanguage\":\"pt-BR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/www.biosyn.com.br\/nuxcell\/qual-a-importancia-da-taurina-para-gatos\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"pt-BR\",\"@id\":\"https:\/\/www.biosyn.com.br\/nuxcell\/qual-a-importancia-da-taurina-para-gatos\/#primaryimage\",\"url\":\"https:\/\/www.biosyn.com.br\/nuxcell\/wp-content\/uploads\/sites\/2\/2022\/09\/adorable-kitty-with-monochrome-wall-her-scaled-1.jpg\",\"contentUrl\":\"https:\/\/www.biosyn.com.br\/nuxcell\/wp-content\/uploads\/sites\/2\/2022\/09\/adorable-kitty-with-monochrome-wall-her-scaled-1.jpg\",\"width\":2560,\"height\":1829},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/www.biosyn.com.br\/nuxcell\/qual-a-importancia-da-taurina-para-gatos\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"In\u00edcio\",\"item\":\"https:\/\/www.biosyn.com.br\/nuxcell\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Qual a import\u00e2ncia da taurina para gatos?\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/www.biosyn.com.br\/nuxcell\/#website\",\"url\":\"https:\/\/www.biosyn.com.br\/nuxcell\/\",\"name\":\"NUXCELL\u00ae | Muito mais que vitamina para cachorro e gato!\",\"description\":\"NUXCELL\u00ae \u00e9 um simbi\u00f3tico imunomodulador exclusivo para c\u00e3es e gatos. Fortalece as defesas do organismo e fornece nutrientes estrat\u00e9gicos para a sa\u00fade pet.\",\"publisher\":{\"@id\":\"https:\/\/www.biosyn.com.br\/nuxcell\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/www.biosyn.com.br\/nuxcell\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"pt-BR\"},{\"@type\":\"Organization\",\"@id\":\"https:\/\/www.biosyn.com.br\/nuxcell\/#organization\",\"name\":\"NUXCELL\u00ae | Muito mais que vitamina para cachorro e gato!\",\"url\":\"https:\/\/www.biosyn.com.br\/nuxcell\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"pt-BR\",\"@id\":\"https:\/\/www.biosyn.com.br\/nuxcell\/#\/schema\/logo\/image\/\",\"url\":\"https:\/\/www.biosyn.com.br\/nuxcell\/wp-content\/uploads\/sites\/2\/2024\/07\/nuxcell_logo-e1721911131146.png\",\"contentUrl\":\"https:\/\/www.biosyn.com.br\/nuxcell\/wp-content\/uploads\/sites\/2\/2024\/07\/nuxcell_logo-e1721911131146.png\",\"width\":550,\"height\":122,\"caption\":\"NUXCELL\u00ae | Muito mais que vitamina para cachorro e gato!\"},\"image\":{\"@id\":\"https:\/\/www.biosyn.com.br\/nuxcell\/#\/schema\/logo\/image\/\"}},{\"@type\":\"Person\",\"@id\":\"https:\/\/www.biosyn.com.br\/nuxcell\/#\/schema\/person\/be2390874bdf6faf4777647b519e5141\",\"name\":\"BioSyn\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"pt-BR\",\"@id\":\"https:\/\/www.biosyn.com.br\/nuxcell\/#\/schema\/person\/image\/\",\"url\":\"https:\/\/secure.gravatar.com\/avatar\/9bfc9c12abb8906f5e67400cc2a2c0eff002384588f8b12c2106a45da6d6c84c?s=96&d=mm&r=g\",\"contentUrl\":\"https:\/\/secure.gravatar.com\/avatar\/9bfc9c12abb8906f5e67400cc2a2c0eff002384588f8b12c2106a45da6d6c84c?s=96&d=mm&r=g\",\"caption\":\"BioSyn\"},\"description\":\"Somos especialistas no desenvolvimento e produ\u00e7\u00e3o de simbi\u00f3ticos imunomoduladores, suplementos que combinam probi\u00f3ticos e prebi\u00f3ticos associados a nutrientes essenciais para a sa\u00fade animal.\",\"sameAs\":[\"https:\/\/www.nuxcell.com.br\/wp-admin\"],\"url\":\"https:\/\/www.biosyn.com.br\/nuxcell\/author\/marketing\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Qual a import\u00e2ncia da taurina para gatos? - NUXCELL\u00ae | Muito mais que vitamina para cachorro e gato!","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.biosyn.com.br\/nuxcell\/qual-a-importancia-da-taurina-para-gatos\/","og_locale":"pt_BR","og_type":"article","og_title":"Qual a import\u00e2ncia da taurina para gatos? - NUXCELL\u00ae | Muito mais que vitamina para cachorro e gato!","og_description":"Os amino\u00e1cidos n\u00e3o essenciais s\u00e3o os que o pr\u00f3prio organismo sintetiza, enquanto os essenciais n\u00e3o s\u00e3o produzidos pelo organismo e precisam ser inclu\u00eddos nas dietas. Para que serve taurina em gatos? Grande parte dos mam\u00edferos sintetiza a taurina, inclusive os seres humanos. Por\u00e9m, os gatos n\u00e3o produzem em quantidades suficientes, e \u00e9 por isso que [&hellip;]","og_url":"https:\/\/www.biosyn.com.br\/nuxcell\/qual-a-importancia-da-taurina-para-gatos\/","og_site_name":"NUXCELL\u00ae | Muito mais que vitamina para cachorro e gato!","article_published_time":"2022-09-22T17:15:50+00:00","og_image":[{"width":2560,"height":1829,"url":"https:\/\/www.biosyn.com.br\/nuxcell\/wp-content\/uploads\/sites\/2\/2022\/09\/adorable-kitty-with-monochrome-wall-her-scaled-1.jpg","type":"image\/jpeg"}],"author":"BioSyn","twitter_card":"summary_large_image","twitter_misc":{"Escrito por":"BioSyn","Est. tempo de leitura":"2 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/www.biosyn.com.br\/nuxcell\/qual-a-importancia-da-taurina-para-gatos\/#article","isPartOf":{"@id":"https:\/\/www.biosyn.com.br\/nuxcell\/qual-a-importancia-da-taurina-para-gatos\/"},"author":{"name":"BioSyn","@id":"https:\/\/www.biosyn.com.br\/nuxcell\/#\/schema\/person\/be2390874bdf6faf4777647b519e5141"},"headline":"Qual a import\u00e2ncia da taurina para gatos?","datePublished":"2022-09-22T17:15:50+00:00","mainEntityOfPage":{"@id":"https:\/\/www.biosyn.com.br\/nuxcell\/qual-a-importancia-da-taurina-para-gatos\/"},"wordCount":326,"publisher":{"@id":"https:\/\/www.biosyn.com.br\/nuxcell\/#organization"},"image":{"@id":"https:\/\/www.biosyn.com.br\/nuxcell\/qual-a-importancia-da-taurina-para-gatos\/#primaryimage"},"thumbnailUrl":"https:\/\/www.biosyn.com.br\/nuxcell\/wp-content\/uploads\/sites\/2\/2022\/09\/adorable-kitty-with-monochrome-wall-her-scaled-1.jpg","keywords":["nuxcell fel"],"articleSection":["Nutri\u00e7\u00e3o","Sa\u00fade"],"inLanguage":"pt-BR"},{"@type":"WebPage","@id":"https:\/\/www.biosyn.com.br\/nuxcell\/qual-a-importancia-da-taurina-para-gatos\/","url":"https:\/\/www.biosyn.com.br\/nuxcell\/qual-a-importancia-da-taurina-para-gatos\/","name":"Qual a import\u00e2ncia da taurina para gatos? - NUXCELL\u00ae | Muito mais que vitamina para cachorro e gato!","isPartOf":{"@id":"https:\/\/www.biosyn.com.br\/nuxcell\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.biosyn.com.br\/nuxcell\/qual-a-importancia-da-taurina-para-gatos\/#primaryimage"},"image":{"@id":"https:\/\/www.biosyn.com.br\/nuxcell\/qual-a-importancia-da-taurina-para-gatos\/#primaryimage"},"thumbnailUrl":"https:\/\/www.biosyn.com.br\/nuxcell\/wp-content\/uploads\/sites\/2\/2022\/09\/adorable-kitty-with-monochrome-wall-her-scaled-1.jpg","datePublished":"2022-09-22T17:15:50+00:00","breadcrumb":{"@id":"https:\/\/www.biosyn.com.br\/nuxcell\/qual-a-importancia-da-taurina-para-gatos\/#breadcrumb"},"inLanguage":"pt-BR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.biosyn.com.br\/nuxcell\/qual-a-importancia-da-taurina-para-gatos\/"]}]},{"@type":"ImageObject","inLanguage":"pt-BR","@id":"https:\/\/www.biosyn.com.br\/nuxcell\/qual-a-importancia-da-taurina-para-gatos\/#primaryimage","url":"https:\/\/www.biosyn.com.br\/nuxcell\/wp-content\/uploads\/sites\/2\/2022\/09\/adorable-kitty-with-monochrome-wall-her-scaled-1.jpg","contentUrl":"https:\/\/www.biosyn.com.br\/nuxcell\/wp-content\/uploads\/sites\/2\/2022\/09\/adorable-kitty-with-monochrome-wall-her-scaled-1.jpg","width":2560,"height":1829},{"@type":"BreadcrumbList","@id":"https:\/\/www.biosyn.com.br\/nuxcell\/qual-a-importancia-da-taurina-para-gatos\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"In\u00edcio","item":"https:\/\/www.biosyn.com.br\/nuxcell\/"},{"@type":"ListItem","position":2,"name":"Qual a import\u00e2ncia da taurina para gatos?"}]},{"@type":"WebSite","@id":"https:\/\/www.biosyn.com.br\/nuxcell\/#website","url":"https:\/\/www.biosyn.com.br\/nuxcell\/","name":"NUXCELL\u00ae | Muito mais que vitamina para cachorro e gato!","description":"NUXCELL\u00ae \u00e9 um simbi\u00f3tico imunomodulador exclusivo para c\u00e3es e gatos. Fortalece as defesas do organismo e fornece nutrientes estrat\u00e9gicos para a sa\u00fade pet.","publisher":{"@id":"https:\/\/www.biosyn.com.br\/nuxcell\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.biosyn.com.br\/nuxcell\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"pt-BR"},{"@type":"Organization","@id":"https:\/\/www.biosyn.com.br\/nuxcell\/#organization","name":"NUXCELL\u00ae | Muito mais que vitamina para cachorro e gato!","url":"https:\/\/www.biosyn.com.br\/nuxcell\/","logo":{"@type":"ImageObject","inLanguage":"pt-BR","@id":"https:\/\/www.biosyn.com.br\/nuxcell\/#\/schema\/logo\/image\/","url":"https:\/\/www.biosyn.com.br\/nuxcell\/wp-content\/uploads\/sites\/2\/2024\/07\/nuxcell_logo-e1721911131146.png","contentUrl":"https:\/\/www.biosyn.com.br\/nuxcell\/wp-content\/uploads\/sites\/2\/2024\/07\/nuxcell_logo-e1721911131146.png","width":550,"height":122,"caption":"NUXCELL\u00ae | Muito mais que vitamina para cachorro e gato!"},"image":{"@id":"https:\/\/www.biosyn.com.br\/nuxcell\/#\/schema\/logo\/image\/"}},{"@type":"Person","@id":"https:\/\/www.biosyn.com.br\/nuxcell\/#\/schema\/person\/be2390874bdf6faf4777647b519e5141","name":"BioSyn","image":{"@type":"ImageObject","inLanguage":"pt-BR","@id":"https:\/\/www.biosyn.com.br\/nuxcell\/#\/schema\/person\/image\/","url":"https:\/\/secure.gravatar.com\/avatar\/9bfc9c12abb8906f5e67400cc2a2c0eff002384588f8b12c2106a45da6d6c84c?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/9bfc9c12abb8906f5e67400cc2a2c0eff002384588f8b12c2106a45da6d6c84c?s=96&d=mm&r=g","caption":"BioSyn"},"description":"Somos especialistas no desenvolvimento e produ\u00e7\u00e3o de simbi\u00f3ticos imunomoduladores, suplementos que combinam probi\u00f3ticos e prebi\u00f3ticos associados a nutrientes essenciais para a sa\u00fade animal.","sameAs":["https:\/\/www.nuxcell.com.br\/wp-admin"],"url":"https:\/\/www.biosyn.com.br\/nuxcell\/author\/marketing\/"}]}},"_links":{"self":[{"href":"https:\/\/www.biosyn.com.br\/nuxcell\/wp-json\/wp\/v2\/posts\/16295","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.biosyn.com.br\/nuxcell\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.biosyn.com.br\/nuxcell\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.biosyn.com.br\/nuxcell\/wp-json\/wp\/v2\/users\/4"}],"replies":[{"embeddable":true,"href":"https:\/\/www.biosyn.com.br\/nuxcell\/wp-json\/wp\/v2\/comments?post=16295"}],"version-history":[{"count":0,"href":"https:\/\/www.biosyn.com.br\/nuxcell\/wp-json\/wp\/v2\/posts\/16295\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.biosyn.com.br\/nuxcell\/wp-json\/wp\/v2\/media\/16296"}],"wp:attachment":[{"href":"https:\/\/www.biosyn.com.br\/nuxcell\/wp-json\/wp\/v2\/media?parent=16295"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.biosyn.com.br\/nuxcell\/wp-json\/wp\/v2\/categories?post=16295"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.biosyn.com.br\/nuxcell\/wp-json\/wp\/v2\/tags?post=16295"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}