{"id":17408,"date":"2023-08-22T17:24:09","date_gmt":"2023-08-22T20:24:09","guid":{"rendered":"https:\/\/www.nuxcell.com.br?p=17408"},"modified":"2024-05-30T13:12:24","modified_gmt":"2024-05-30T13:12:24","slug":"resultados-nuxcell-nuxp23","status":"publish","type":"post","link":"https:\/\/www.biosyn.com.br\/nuxcell\/resultados-nuxcell-nuxp23\/","title":{"rendered":"Resultados de NUXCELL no Painel T\u00e9cnico do NUXP23"},"content":{"rendered":"<p>O NUXPERIENCE 2023 reuniu profissionais do mercado Pet &amp; Vet para mais uma imers\u00e3o repleta de conhecimento, amor pelos animais e, \u00e9 claro, resultados dos produtos NUXCELL!<\/p>\n<p>Organizado pela BioSyn Sa\u00fade Animal para promover uma experi\u00eancia memor\u00e1vel e exclusiva para parceiros NUXCELL, o <a href=\"https:\/\/www.biosyn.com.br\/nuxcellnuxperience2023\/\">evento<\/a> reuniu tr\u00eas especialistas para falarem sobre os produtos NUXCELL, tanto da linha tradicional como da linha \u00dfeta.<\/p>\n<p>Siga a leitura para entender mais sobre tudo o que eles apresentaram no Painel T\u00e9cnico NUXCELL!<\/p>\n<p><img fetchpriority=\"high\" decoding=\"async\" class=\"aligncenter wp-image-17450 \" src=\"https:\/\/www.biosyn.com.br\/nuxcellwp-content\/uploads\/sites\/2\/2023\/08\/Nuxcell-157-1-1024x683.webp\" alt=\"Distribuidores NUXP23\" width=\"536\" height=\"358\" srcset=\"https:\/\/www.biosyn.com.br\/nuxcell\/wp-content\/uploads\/sites\/2\/2023\/08\/Nuxcell-157-1-1024x683.webp 1024w, https:\/\/www.biosyn.com.br\/nuxcell\/wp-content\/uploads\/sites\/2\/2023\/08\/Nuxcell-157-1-300x200.webp 300w, https:\/\/www.biosyn.com.br\/nuxcell\/wp-content\/uploads\/sites\/2\/2023\/08\/Nuxcell-157-1-768x512.webp 768w, https:\/\/www.biosyn.com.br\/nuxcell\/wp-content\/uploads\/sites\/2\/2023\/08\/Nuxcell-157-1-1536x1024.webp 1536w, https:\/\/www.biosyn.com.br\/nuxcell\/wp-content\/uploads\/sites\/2\/2023\/08\/Nuxcell-157-1-600x400.webp 600w, https:\/\/www.biosyn.com.br\/nuxcell\/wp-content\/uploads\/sites\/2\/2023\/08\/Nuxcell-157-1.jpg 1620w\" sizes=\"(max-width: 536px) 100vw, 536px\" \/><\/p>\n<p>&nbsp;<\/p>\n<h2>Tecnologias de processo e protocolos de uso<\/h2>\n<p>Quem abriu o Painel T\u00e9cnico NUXCELL foi a engenheira de alimentos, Marina Piola Rossetto, abordando os principais pilares da formula\u00e7\u00e3o equilibrada de um produto como NUXCELL.<\/p>\n<p>Esses quatro pilares s\u00e3o <strong>nutri\u00e7\u00e3o, seguran\u00e7a, ades\u00e3o e aspectos sensoriais.<\/strong><\/p>\n<ul>\n<li><strong>Nutri\u00e7\u00e3o\u00a0<\/strong>envolve aspectos como a forma f\u00edsica do produto, como ele ser\u00e1 apresentado, as suas limita\u00e7\u00f5es e viabilidade. Entre os fatores considerados, Marina cita a sele\u00e7\u00e3o e intera\u00e7\u00e3o dos nutrientes entre si, al\u00e9m da adequa\u00e7\u00e3o deles com os \u00f3rg\u00e3os regentes.<\/li>\n<\/ul>\n<blockquote><p>&#8220;Eu preciso entender <em>quanto<\/em> eu vou fornecer para o meu animal e o <em>qu\u00ea<\/em> eu quero fornecer de nutrientes essenciais. Nem sempre vai caber em uma mesma f\u00f3rmula, por isso, a gente faz <strong>produtos espec\u00edficos.<\/strong>&#8221; ela explica.<\/p><\/blockquote>\n<figure id=\"attachment_17453\" aria-describedby=\"caption-attachment-17453\" style=\"width: 428px\" class=\"wp-caption aligncenter\"><img decoding=\"async\" class=\"wp-image-17453 \" src=\"https:\/\/www.biosyn.com.br\/nuxcellwp-content\/uploads\/sites\/2\/2023\/08\/Nuxcell-199-1-819x1024.webp\" alt=\"Resultados Painel T\u00e9cnico NUXP23\" width=\"428\" height=\"535\" srcset=\"https:\/\/www.biosyn.com.br\/nuxcell\/wp-content\/uploads\/sites\/2\/2023\/08\/Nuxcell-199-1-819x1024.webp 819w, https:\/\/www.biosyn.com.br\/nuxcell\/wp-content\/uploads\/sites\/2\/2023\/08\/Nuxcell-199-1-240x300.webp 240w, https:\/\/www.biosyn.com.br\/nuxcell\/wp-content\/uploads\/sites\/2\/2023\/08\/Nuxcell-199-1-768x960.webp 768w, https:\/\/www.biosyn.com.br\/nuxcell\/wp-content\/uploads\/sites\/2\/2023\/08\/Nuxcell-199-1-600x750.webp 600w, https:\/\/www.biosyn.com.br\/nuxcell\/wp-content\/uploads\/sites\/2\/2023\/08\/Nuxcell-199-1.jpg 864w\" sizes=\"(max-width: 428px) 100vw, 428px\" \/><figcaption id=\"caption-attachment-17453\" class=\"wp-caption-text\">Marina Piola &#8211; Engenheira de alimentos de NUXCELL<\/figcaption><\/figure>\n<p>&nbsp;<\/p>\n<ul>\n<li><strong>Seguran\u00e7a<\/strong> considera a efic\u00e1cia e o hist\u00f3rico de uso dos nutrientes, al\u00e9m de avaliar se ele \u00e9 seguro mesmo para a esp\u00e9cie-alvo.<\/li>\n<\/ul>\n<blockquote><p>&#8220;Nada \u00e9 por acaso. Nada entra na formula\u00e7\u00e3o por falta de estudo ou evid\u00eancia. A presen\u00e7a deles (insumos) \u00e9 para equilibrar os quatro pilares e entregar um <strong>produto seguro<\/strong>.&#8221;<\/p><\/blockquote>\n<ul>\n<li><strong>Ades\u00e3o<\/strong> \u00e9 tudo, nas palavras de Marina. Afinal, leva em conta as caracter\u00edsticas intr\u00ednsecas do produto e a adequa\u00e7\u00e3o dele \u00e0s situa\u00e7\u00f5es de uso.<\/li>\n<\/ul>\n<p>&nbsp;<\/p>\n<ul>\n<li><strong>Aspectos sensoriais<\/strong>, por fim, abordam a percep\u00e7\u00e3o do produto frente ao cliente. Por isso, ela explica que NUXCELL trabalha visando uma produ\u00e7\u00e3o com foco padronizado.<\/li>\n<\/ul>\n<blockquote><p>&#8220;A melhor prescri\u00e7\u00e3o n\u00e3o \u00e9 com o produto mais caro na maior dosagem, \u00e9 aquela que o paciente adere com o acompanhamento adequado.&#8221; ela finaliza.<\/p><\/blockquote>\n<p>&nbsp;<\/p>\n<h2>Resultados em campo com NUXCELL \u00dfeta<\/h2>\n<p>Na sequ\u00eancia, quem trouxe os resultados de NUXCELL \u00dfeta foi a m\u00e9dica veterin\u00e1ria e coordenadora t\u00e9cnica, Dra. D\u00e9bora Sargiani.<\/p>\n<p>Primeiramente, D\u00e9bora resgata a principal explica\u00e7\u00e3o sobre a linha \u00dfeta, que faz refer\u00eancia a um dos componentes principais dos produtos NUXCELL: a beta glucana <span style=\"font-weight: 400;\">\u2014 uma chave natural para o est\u00edmulo do sistema imune.<\/span><\/p>\n<blockquote><p>&#8220;A linha NUXCELL \u00dfeta vem trabalhando tudo o que j\u00e1 se conhece dos produtos NUXCELL na parte imunol\u00f3gica e no trato gastrointestinal, mas\u00a0<strong>muito<\/strong> voltada para a a\u00e7\u00e3o da beta glucana frente \u00e0 imunidade e na inflama\u00e7\u00e3o.&#8221;<\/p><\/blockquote>\n<figure id=\"attachment_17451\" aria-describedby=\"caption-attachment-17451\" style=\"width: 428px\" class=\"wp-caption aligncenter\"><img decoding=\"async\" class=\"wp-image-17451 \" src=\"https:\/\/www.biosyn.com.br\/nuxcellwp-content\/uploads\/sites\/2\/2023\/08\/Nuxcell-227-1-819x1024.webp\" alt=\"Painel T\u00e9cnico NUXP23 \" width=\"428\" height=\"535\" srcset=\"https:\/\/www.biosyn.com.br\/nuxcell\/wp-content\/uploads\/sites\/2\/2023\/08\/Nuxcell-227-1-819x1024.webp 819w, https:\/\/www.biosyn.com.br\/nuxcell\/wp-content\/uploads\/sites\/2\/2023\/08\/Nuxcell-227-1-240x300.webp 240w, https:\/\/www.biosyn.com.br\/nuxcell\/wp-content\/uploads\/sites\/2\/2023\/08\/Nuxcell-227-1-768x960.webp 768w, https:\/\/www.biosyn.com.br\/nuxcell\/wp-content\/uploads\/sites\/2\/2023\/08\/Nuxcell-227-1-600x750.webp 600w, https:\/\/www.biosyn.com.br\/nuxcell\/wp-content\/uploads\/sites\/2\/2023\/08\/Nuxcell-227-1.jpg 864w\" sizes=\"(max-width: 428px) 100vw, 428px\" \/><figcaption id=\"caption-attachment-17451\" class=\"wp-caption-text\">D\u00e9bora Sargiani &#8211; Coordenadora T\u00e9cnica de NUXCELL e m\u00e9dica veterin\u00e1ria<\/figcaption><\/figure>\n<p>&nbsp;<\/p>\n<p>Ela refor\u00e7a que houve acompanhamento intenso dos animais, para entender al\u00e9m das an\u00e1lises cl\u00ednicas e dos relatos de tutores. Os resultados de NUXCELL \u00dfeta ainda esclareceram sua a\u00e7\u00e3o frente \u00e0s citocinas.<\/p>\n<p>Os resultados dos casos de NUXCELL \u00dfeta evidenciam, na pr\u00e1tica, os benef\u00edcios da beta glucana.<\/p>\n<ul>\n<li><strong>NUXCELL \u00dfeta Cardio<\/strong> traz, entre os diversos resultados positivos, a a\u00e7\u00e3o altamente eficaz na redu\u00e7\u00e3o de <strong>LDL\u00a0<\/strong>(colesterol ruim) e aumento do\u00a0<strong>HDL<\/strong> (colesterol bom). Al\u00e9m disso, apresenta a redu\u00e7\u00e3o expressiva no n\u00famero de triglicer\u00eddeos e das citocinas inflamat\u00f3rias.<\/li>\n<\/ul>\n<p>&nbsp;<\/p>\n<ul>\n<li><strong>NUXCELL \u00dfeta Diabetic<\/strong> evidencia a redu\u00e7\u00e3o dos n\u00edveis de frutosamina, um a\u00e7\u00facar que estava em descontrole no caso de uma paciente, mesmo ela j\u00e1 tratando o diabetes. Al\u00e9m disso, os casos estudados tamb\u00e9m apontam forte diminui\u00e7\u00e3o de citocinas inflamat\u00f3rias como TNF\u03b1, IL-6 e IL-1 \u03b2.<\/li>\n<\/ul>\n<p>&nbsp;<\/p>\n<ul>\n<li><strong>NUXCELL \u00dfeta Osteo<\/strong> apresentou, entre os resultados, a diminui\u00e7\u00e3o dos gases intestinais e das dores de uma paciente tetrapl\u00e9gica. Al\u00e9m disso, tamb\u00e9m contribuiu com o aumento do <strong>HDL<\/strong>, a redu\u00e7\u00e3o de <strong>LDL<\/strong>, das citocinas inflamat\u00f3rias e dos triglicer\u00eddeos.<\/li>\n<\/ul>\n<p>&nbsp;<\/p>\n<h2>Novos resultados obtidos com a linha NUXCELL<\/h2>\n<p>O encerramento do Painel T\u00e9cnico ficou a cargo do diretor de pesquisa, Dr. Gabriel Jesus, que refor\u00e7ou a import\u00e2ncia do intestino na sa\u00fade dos animais. Afinal, o \u00f3rg\u00e3o vai muito al\u00e9m da fun\u00e7\u00e3o de absor\u00e7\u00e3o dos nutrientes, tendo uma fun\u00e7\u00e3o de barreira e impactando cerca de 60% da imunidade dos animais.<\/p>\n<blockquote><p>&#8220;Se o intestino n\u00e3o est\u00e1 \u00edntegro, ele tamb\u00e9m n\u00e3o estar\u00e1 respondendo \u00e0 altura dessa fun\u00e7\u00e3o imunol\u00f3gica. Mas, ent\u00e3o, como ajudar na imunomodula\u00e7\u00e3o do intestino? NUXCELL!&#8221; ele enfatiza.<\/p><\/blockquote>\n<figure id=\"attachment_17452\" aria-describedby=\"caption-attachment-17452\" style=\"width: 428px\" class=\"wp-caption aligncenter\"><img loading=\"lazy\" decoding=\"async\" class=\"wp-image-17452 \" src=\"https:\/\/www.biosyn.com.br\/nuxcellwp-content\/uploads\/sites\/2\/2023\/08\/Nuxcell-299-1-819x1024.webp\" alt=\"Resultados Ensaios Cl\u00ednicos NUXP23\" width=\"428\" height=\"535\" srcset=\"https:\/\/www.biosyn.com.br\/nuxcell\/wp-content\/uploads\/sites\/2\/2023\/08\/Nuxcell-299-1-819x1024.webp 819w, https:\/\/www.biosyn.com.br\/nuxcell\/wp-content\/uploads\/sites\/2\/2023\/08\/Nuxcell-299-1-240x300.webp 240w, https:\/\/www.biosyn.com.br\/nuxcell\/wp-content\/uploads\/sites\/2\/2023\/08\/Nuxcell-299-1-768x960.webp 768w, https:\/\/www.biosyn.com.br\/nuxcell\/wp-content\/uploads\/sites\/2\/2023\/08\/Nuxcell-299-1-600x750.webp 600w, https:\/\/www.biosyn.com.br\/nuxcell\/wp-content\/uploads\/sites\/2\/2023\/08\/Nuxcell-299-1.jpg 864w\" sizes=\"(max-width: 428px) 100vw, 428px\" \/><figcaption id=\"caption-attachment-17452\" class=\"wp-caption-text\">Gabriel Jesus &#8211; Diretor de Pesquisa e Desenvolvimento de NUXCELL<\/figcaption><\/figure>\n<p>&nbsp;<\/p>\n<p>Para esclarecer os resultados de NUXCELL, ele trouxe os dados dos novos ensaios cl\u00ednicos sobre os produtos NUXCELL Neo e NUXCELL Plus.<\/p>\n<p>O ensaio cl\u00ednico de <strong>NUXCELL Neo<\/strong> explorou a a\u00e7\u00e3o do simbi\u00f3tico no per\u00edodo de vacina\u00e7\u00e3o e os resultados n\u00e3o poderiam ser melhores!<\/p>\n<p>Comprovou-se que NUXCELL Neo \u00e9 capaz de potencializar a produ\u00e7\u00e3o de anticorpos, em um per\u00edodo de 21 dias ap\u00f3s a vacina\u00e7\u00e3o. Assim, a resposta vacinal foi 2,34x maior em compara\u00e7\u00e3o aos animais sem suplementa\u00e7\u00e3o.<\/p>\n<p>Al\u00e9m disso, tamb\u00e9m foi atestada a a\u00e7\u00e3o imunomoduladora no intestino frente \u00e0 inflama\u00e7\u00e3o, diminuindo os danos oxidativos ao \u00f3rg\u00e3o.<\/p>\n<p>J\u00e1 o ensaio cl\u00ednico de <strong>NUXCELL Plus<\/strong>, al\u00e9m de evidenciar o potencial de imunomodula\u00e7\u00e3o, tamb\u00e9m comprovou que o simbi\u00f3tico \u00e9 altamente eficaz no acompanhamento <strong>p\u00f3s-cir\u00fargico.<\/strong><\/p>\n<p>Al\u00e9m da redu\u00e7\u00e3o no n\u00famero de citocinas inflamat\u00f3rias, NUXCELL Plus apresentou uma a\u00e7\u00e3o impressionante na cicatriza\u00e7\u00e3o dos animais. E isso, de acordo com Gabriel, se deve ao refor\u00e7o imunol\u00f3gico dado por NUXCELL.<\/p>\n<p>Por fim, ambos os ensaios tamb\u00e9m enfatizam os benef\u00edcios comportamentais nos animais, que demonstraram menor ansiedade e sintomas de dor.<\/p>\n<p>&nbsp;<\/p>\n<h2>NUXPERIENCE 2023<\/h2>\n<p>Este foi um dos pontos altos da programa\u00e7\u00e3o de 12h do evento, que contou com 150 convidados de todo o pa\u00eds. De forma geral, se conseguiu compreender, visualizar e comprovar os resultados positivos de NUXCELL e a a\u00e7\u00e3o imunomoduladora de todos os produtos das linhas tradicional e \u00dfeta.<\/p>\n<p><a href=\"https:\/\/drive.google.com\/drive\/folders\/1CVSC3Re5R5_RYE3AX77jJPH8Tm_ljBSE?usp=drive_link\"><strong>Confira a galeria de fotos!<\/strong><\/a><\/p>\n","protected":false},"excerpt":{"rendered":"<p>O NUXPERIENCE 2023 reuniu profissionais do mercado Pet &amp; Vet para mais uma imers\u00e3o repleta de conhecimento, amor pelos animais e, \u00e9 claro, resultados dos produtos NUXCELL! Organizado pela BioSyn Sa\u00fade Animal para promover uma experi\u00eancia memor\u00e1vel e exclusiva para parceiros NUXCELL, o evento reuniu tr\u00eas especialistas para falarem sobre os produtos NUXCELL, tanto da [&hellip;]<\/p>\n","protected":false},"author":188,"featured_media":17454,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"footnotes":""},"categories":[84],"tags":[111,112,113,114,115,107,116,117,48,118,119],"class_list":["post-17408","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-noticias","tag-evento","tag-imunomodulacao","tag-nuxcell","tag-nuxp23","tag-nuxperience-2023","tag-pets","tag-prebioticos","tag-probioticos","tag-saude-animal","tag-simbiotico","tag-tutores"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v26.2 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>Resultados de NUXCELL no Painel T\u00e9cnico do NUXP23 - NUXCELL\u00ae | Muito mais que vitamina para cachorro e gato!<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.biosyn.com.br\/nuxcell\/resultados-nuxcell-nuxp23\/\" \/>\n<meta property=\"og:locale\" content=\"pt_BR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Resultados de NUXCELL no Painel T\u00e9cnico do NUXP23 - NUXCELL\u00ae | Muito mais que vitamina para cachorro e gato!\" \/>\n<meta property=\"og:description\" content=\"O NUXPERIENCE 2023 reuniu profissionais do mercado Pet &amp; Vet para mais uma imers\u00e3o repleta de conhecimento, amor pelos animais e, \u00e9 claro, resultados dos produtos NUXCELL! Organizado pela BioSyn Sa\u00fade Animal para promover uma experi\u00eancia memor\u00e1vel e exclusiva para parceiros NUXCELL, o evento reuniu tr\u00eas especialistas para falarem sobre os produtos NUXCELL, tanto da [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.biosyn.com.br\/nuxcell\/resultados-nuxcell-nuxp23\/\" \/>\n<meta property=\"og:site_name\" content=\"NUXCELL\u00ae | Muito mais que vitamina para cachorro e gato!\" \/>\n<meta property=\"article:published_time\" content=\"2023-08-22T20:24:09+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2024-05-30T13:12:24+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.biosyn.com.br\/nuxcell\/wp-content\/uploads\/sites\/2\/2023\/08\/Nuxcell-283-1.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"1620\" \/>\n\t<meta property=\"og:image:height\" content=\"1080\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"Canal Pet\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t<meta name=\"twitter:data1\" content=\"Canal Pet\" \/>\n\t<meta name=\"twitter:label2\" content=\"Est. tempo de leitura\" \/>\n\t<meta name=\"twitter:data2\" content=\"6 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\/\/www.biosyn.com.br\/nuxcell\/resultados-nuxcell-nuxp23\/#article\",\"isPartOf\":{\"@id\":\"https:\/\/www.biosyn.com.br\/nuxcell\/resultados-nuxcell-nuxp23\/\"},\"author\":{\"name\":\"Canal Pet\",\"@id\":\"https:\/\/www.biosyn.com.br\/nuxcell\/#\/schema\/person\/f099e916bdf8abf07f021527aedcb23d\"},\"headline\":\"Resultados de NUXCELL no Painel T\u00e9cnico do NUXP23\",\"datePublished\":\"2023-08-22T20:24:09+00:00\",\"dateModified\":\"2024-05-30T13:12:24+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\/\/www.biosyn.com.br\/nuxcell\/resultados-nuxcell-nuxp23\/\"},\"wordCount\":1086,\"publisher\":{\"@id\":\"https:\/\/www.biosyn.com.br\/nuxcell\/#organization\"},\"image\":{\"@id\":\"https:\/\/www.biosyn.com.br\/nuxcell\/resultados-nuxcell-nuxp23\/#primaryimage\"},\"thumbnailUrl\":\"https:\/\/www.biosyn.com.br\/nuxcell\/wp-content\/uploads\/sites\/2\/2023\/08\/Nuxcell-283-1.jpg\",\"keywords\":[\"evento\",\"imunomodula\u00e7\u00e3o\",\"nuxcell\",\"nuxp23\",\"nuxperience 2023\",\"pets\",\"prebi\u00f3ticos\",\"probi\u00f3ticos\",\"sa\u00fade animal\",\"simbi\u00f3tico\",\"tutores\"],\"articleSection\":[\"Not\u00edcias\"],\"inLanguage\":\"pt-BR\"},{\"@type\":\"WebPage\",\"@id\":\"https:\/\/www.biosyn.com.br\/nuxcell\/resultados-nuxcell-nuxp23\/\",\"url\":\"https:\/\/www.biosyn.com.br\/nuxcell\/resultados-nuxcell-nuxp23\/\",\"name\":\"Resultados de NUXCELL no Painel T\u00e9cnico do NUXP23 - NUXCELL\u00ae | Muito mais que vitamina para cachorro e gato!\",\"isPartOf\":{\"@id\":\"https:\/\/www.biosyn.com.br\/nuxcell\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\/\/www.biosyn.com.br\/nuxcell\/resultados-nuxcell-nuxp23\/#primaryimage\"},\"image\":{\"@id\":\"https:\/\/www.biosyn.com.br\/nuxcell\/resultados-nuxcell-nuxp23\/#primaryimage\"},\"thumbnailUrl\":\"https:\/\/www.biosyn.com.br\/nuxcell\/wp-content\/uploads\/sites\/2\/2023\/08\/Nuxcell-283-1.jpg\",\"datePublished\":\"2023-08-22T20:24:09+00:00\",\"dateModified\":\"2024-05-30T13:12:24+00:00\",\"breadcrumb\":{\"@id\":\"https:\/\/www.biosyn.com.br\/nuxcell\/resultados-nuxcell-nuxp23\/#breadcrumb\"},\"inLanguage\":\"pt-BR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/www.biosyn.com.br\/nuxcell\/resultados-nuxcell-nuxp23\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"pt-BR\",\"@id\":\"https:\/\/www.biosyn.com.br\/nuxcell\/resultados-nuxcell-nuxp23\/#primaryimage\",\"url\":\"https:\/\/www.biosyn.com.br\/nuxcell\/wp-content\/uploads\/sites\/2\/2023\/08\/Nuxcell-283-1.jpg\",\"contentUrl\":\"https:\/\/www.biosyn.com.br\/nuxcell\/wp-content\/uploads\/sites\/2\/2023\/08\/Nuxcell-283-1.jpg\",\"width\":1620,\"height\":1080,\"caption\":\"Painel T\u00e9cnico NUXP23\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/www.biosyn.com.br\/nuxcell\/resultados-nuxcell-nuxp23\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"In\u00edcio\",\"item\":\"https:\/\/www.biosyn.com.br\/nuxcell\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Resultados de NUXCELL no Painel T\u00e9cnico do NUXP23\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/www.biosyn.com.br\/nuxcell\/#website\",\"url\":\"https:\/\/www.biosyn.com.br\/nuxcell\/\",\"name\":\"NUXCELL\u00ae | Muito mais que vitamina para cachorro e gato!\",\"description\":\"NUXCELL\u00ae \u00e9 um simbi\u00f3tico imunomodulador exclusivo para c\u00e3es e gatos. Fortalece as defesas do organismo e fornece nutrientes estrat\u00e9gicos para a sa\u00fade pet.\",\"publisher\":{\"@id\":\"https:\/\/www.biosyn.com.br\/nuxcell\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/www.biosyn.com.br\/nuxcell\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"pt-BR\"},{\"@type\":\"Organization\",\"@id\":\"https:\/\/www.biosyn.com.br\/nuxcell\/#organization\",\"name\":\"NUXCELL\u00ae | Muito mais que vitamina para cachorro e gato!\",\"url\":\"https:\/\/www.biosyn.com.br\/nuxcell\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"pt-BR\",\"@id\":\"https:\/\/www.biosyn.com.br\/nuxcell\/#\/schema\/logo\/image\/\",\"url\":\"https:\/\/www.biosyn.com.br\/nuxcell\/wp-content\/uploads\/sites\/2\/2024\/07\/nuxcell_logo-e1721911131146.png\",\"contentUrl\":\"https:\/\/www.biosyn.com.br\/nuxcell\/wp-content\/uploads\/sites\/2\/2024\/07\/nuxcell_logo-e1721911131146.png\",\"width\":550,\"height\":122,\"caption\":\"NUXCELL\u00ae | Muito mais que vitamina para cachorro e gato!\"},\"image\":{\"@id\":\"https:\/\/www.biosyn.com.br\/nuxcell\/#\/schema\/logo\/image\/\"}},{\"@type\":\"Person\",\"@id\":\"https:\/\/www.biosyn.com.br\/nuxcell\/#\/schema\/person\/f099e916bdf8abf07f021527aedcb23d\",\"name\":\"Canal Pet\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"pt-BR\",\"@id\":\"https:\/\/www.biosyn.com.br\/nuxcell\/#\/schema\/person\/image\/\",\"url\":\"https:\/\/secure.gravatar.com\/avatar\/?s=96&d=mm&r=g\",\"contentUrl\":\"https:\/\/secure.gravatar.com\/avatar\/?s=96&d=mm&r=g\",\"caption\":\"Canal Pet\"},\"url\":\"https:\/\/www.biosyn.com.br\/nuxcell\/author\/canal-pet-3\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Resultados de NUXCELL no Painel T\u00e9cnico do NUXP23 - NUXCELL\u00ae | Muito mais que vitamina para cachorro e gato!","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.biosyn.com.br\/nuxcell\/resultados-nuxcell-nuxp23\/","og_locale":"pt_BR","og_type":"article","og_title":"Resultados de NUXCELL no Painel T\u00e9cnico do NUXP23 - NUXCELL\u00ae | Muito mais que vitamina para cachorro e gato!","og_description":"O NUXPERIENCE 2023 reuniu profissionais do mercado Pet &amp; Vet para mais uma imers\u00e3o repleta de conhecimento, amor pelos animais e, \u00e9 claro, resultados dos produtos NUXCELL! Organizado pela BioSyn Sa\u00fade Animal para promover uma experi\u00eancia memor\u00e1vel e exclusiva para parceiros NUXCELL, o evento reuniu tr\u00eas especialistas para falarem sobre os produtos NUXCELL, tanto da [&hellip;]","og_url":"https:\/\/www.biosyn.com.br\/nuxcell\/resultados-nuxcell-nuxp23\/","og_site_name":"NUXCELL\u00ae | Muito mais que vitamina para cachorro e gato!","article_published_time":"2023-08-22T20:24:09+00:00","article_modified_time":"2024-05-30T13:12:24+00:00","og_image":[{"width":1620,"height":1080,"url":"https:\/\/www.biosyn.com.br\/nuxcell\/wp-content\/uploads\/sites\/2\/2023\/08\/Nuxcell-283-1.jpg","type":"image\/jpeg"}],"author":"Canal Pet","twitter_card":"summary_large_image","twitter_misc":{"Escrito por":"Canal Pet","Est. tempo de leitura":"6 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/www.biosyn.com.br\/nuxcell\/resultados-nuxcell-nuxp23\/#article","isPartOf":{"@id":"https:\/\/www.biosyn.com.br\/nuxcell\/resultados-nuxcell-nuxp23\/"},"author":{"name":"Canal Pet","@id":"https:\/\/www.biosyn.com.br\/nuxcell\/#\/schema\/person\/f099e916bdf8abf07f021527aedcb23d"},"headline":"Resultados de NUXCELL no Painel T\u00e9cnico do NUXP23","datePublished":"2023-08-22T20:24:09+00:00","dateModified":"2024-05-30T13:12:24+00:00","mainEntityOfPage":{"@id":"https:\/\/www.biosyn.com.br\/nuxcell\/resultados-nuxcell-nuxp23\/"},"wordCount":1086,"publisher":{"@id":"https:\/\/www.biosyn.com.br\/nuxcell\/#organization"},"image":{"@id":"https:\/\/www.biosyn.com.br\/nuxcell\/resultados-nuxcell-nuxp23\/#primaryimage"},"thumbnailUrl":"https:\/\/www.biosyn.com.br\/nuxcell\/wp-content\/uploads\/sites\/2\/2023\/08\/Nuxcell-283-1.jpg","keywords":["evento","imunomodula\u00e7\u00e3o","nuxcell","nuxp23","nuxperience 2023","pets","prebi\u00f3ticos","probi\u00f3ticos","sa\u00fade animal","simbi\u00f3tico","tutores"],"articleSection":["Not\u00edcias"],"inLanguage":"pt-BR"},{"@type":"WebPage","@id":"https:\/\/www.biosyn.com.br\/nuxcell\/resultados-nuxcell-nuxp23\/","url":"https:\/\/www.biosyn.com.br\/nuxcell\/resultados-nuxcell-nuxp23\/","name":"Resultados de NUXCELL no Painel T\u00e9cnico do NUXP23 - NUXCELL\u00ae | Muito mais que vitamina para cachorro e gato!","isPartOf":{"@id":"https:\/\/www.biosyn.com.br\/nuxcell\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.biosyn.com.br\/nuxcell\/resultados-nuxcell-nuxp23\/#primaryimage"},"image":{"@id":"https:\/\/www.biosyn.com.br\/nuxcell\/resultados-nuxcell-nuxp23\/#primaryimage"},"thumbnailUrl":"https:\/\/www.biosyn.com.br\/nuxcell\/wp-content\/uploads\/sites\/2\/2023\/08\/Nuxcell-283-1.jpg","datePublished":"2023-08-22T20:24:09+00:00","dateModified":"2024-05-30T13:12:24+00:00","breadcrumb":{"@id":"https:\/\/www.biosyn.com.br\/nuxcell\/resultados-nuxcell-nuxp23\/#breadcrumb"},"inLanguage":"pt-BR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.biosyn.com.br\/nuxcell\/resultados-nuxcell-nuxp23\/"]}]},{"@type":"ImageObject","inLanguage":"pt-BR","@id":"https:\/\/www.biosyn.com.br\/nuxcell\/resultados-nuxcell-nuxp23\/#primaryimage","url":"https:\/\/www.biosyn.com.br\/nuxcell\/wp-content\/uploads\/sites\/2\/2023\/08\/Nuxcell-283-1.jpg","contentUrl":"https:\/\/www.biosyn.com.br\/nuxcell\/wp-content\/uploads\/sites\/2\/2023\/08\/Nuxcell-283-1.jpg","width":1620,"height":1080,"caption":"Painel T\u00e9cnico NUXP23"},{"@type":"BreadcrumbList","@id":"https:\/\/www.biosyn.com.br\/nuxcell\/resultados-nuxcell-nuxp23\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"In\u00edcio","item":"https:\/\/www.biosyn.com.br\/nuxcell\/"},{"@type":"ListItem","position":2,"name":"Resultados de NUXCELL no Painel T\u00e9cnico do NUXP23"}]},{"@type":"WebSite","@id":"https:\/\/www.biosyn.com.br\/nuxcell\/#website","url":"https:\/\/www.biosyn.com.br\/nuxcell\/","name":"NUXCELL\u00ae | Muito mais que vitamina para cachorro e gato!","description":"NUXCELL\u00ae \u00e9 um simbi\u00f3tico imunomodulador exclusivo para c\u00e3es e gatos. Fortalece as defesas do organismo e fornece nutrientes estrat\u00e9gicos para a sa\u00fade pet.","publisher":{"@id":"https:\/\/www.biosyn.com.br\/nuxcell\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.biosyn.com.br\/nuxcell\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"pt-BR"},{"@type":"Organization","@id":"https:\/\/www.biosyn.com.br\/nuxcell\/#organization","name":"NUXCELL\u00ae | Muito mais que vitamina para cachorro e gato!","url":"https:\/\/www.biosyn.com.br\/nuxcell\/","logo":{"@type":"ImageObject","inLanguage":"pt-BR","@id":"https:\/\/www.biosyn.com.br\/nuxcell\/#\/schema\/logo\/image\/","url":"https:\/\/www.biosyn.com.br\/nuxcell\/wp-content\/uploads\/sites\/2\/2024\/07\/nuxcell_logo-e1721911131146.png","contentUrl":"https:\/\/www.biosyn.com.br\/nuxcell\/wp-content\/uploads\/sites\/2\/2024\/07\/nuxcell_logo-e1721911131146.png","width":550,"height":122,"caption":"NUXCELL\u00ae | Muito mais que vitamina para cachorro e gato!"},"image":{"@id":"https:\/\/www.biosyn.com.br\/nuxcell\/#\/schema\/logo\/image\/"}},{"@type":"Person","@id":"https:\/\/www.biosyn.com.br\/nuxcell\/#\/schema\/person\/f099e916bdf8abf07f021527aedcb23d","name":"Canal Pet","image":{"@type":"ImageObject","inLanguage":"pt-BR","@id":"https:\/\/www.biosyn.com.br\/nuxcell\/#\/schema\/person\/image\/","url":"https:\/\/secure.gravatar.com\/avatar\/?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/?s=96&d=mm&r=g","caption":"Canal Pet"},"url":"https:\/\/www.biosyn.com.br\/nuxcell\/author\/canal-pet-3\/"}]}},"_links":{"self":[{"href":"https:\/\/www.biosyn.com.br\/nuxcell\/wp-json\/wp\/v2\/posts\/17408","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.biosyn.com.br\/nuxcell\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.biosyn.com.br\/nuxcell\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.biosyn.com.br\/nuxcell\/wp-json\/wp\/v2\/users\/188"}],"replies":[{"embeddable":true,"href":"https:\/\/www.biosyn.com.br\/nuxcell\/wp-json\/wp\/v2\/comments?post=17408"}],"version-history":[{"count":0,"href":"https:\/\/www.biosyn.com.br\/nuxcell\/wp-json\/wp\/v2\/posts\/17408\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.biosyn.com.br\/nuxcell\/wp-json\/wp\/v2\/media\/17454"}],"wp:attachment":[{"href":"https:\/\/www.biosyn.com.br\/nuxcell\/wp-json\/wp\/v2\/media?parent=17408"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.biosyn.com.br\/nuxcell\/wp-json\/wp\/v2\/categories?post=17408"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.biosyn.com.br\/nuxcell\/wp-json\/wp\/v2\/tags?post=17408"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}